{"id":11737,"date":"2024-08-29T18:37:56","date_gmt":"2024-08-29T18:37:56","guid":{"rendered":"https:\/\/teterete.com\/mx\/?post_type=product&#038;p=11737"},"modified":"2024-08-29T18:37:57","modified_gmt":"2024-08-29T18:37:57","slug":"blusa-orquidea","status":"publish","type":"product","link":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/","title":{"rendered":"Blusa Orqu\u00eddea"},"content":{"rendered":"<p>Estampado original de Pol&amp;Pol hecho con grabado en madera<\/p>\n<p>Lavado en seco \u00fanicamente<\/p>\n<p>Medidas: 65 x 57 cm<\/p>\n<p>100% lino<br \/>\nEstampado hecho a mano<br \/>\nUnitalla<br \/>\nEdici\u00f3n limitada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luce esta blusa artesanal de 100% lino con un delicado estampado de orqu\u00eddea en color salm\u00f3n, grabado a mano en madera. Elegancia y artesan\u00eda en una sola pieza<\/p>\n","protected":false},"featured_media":11738,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":""},"product_brand":[],"product_cat":[1263,61,1012,55],"product_tag":[1947,2462,1030,2463],"class_list":{"0":"post-11737","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-moda-mexicana","7":"product_cat-para_ella","8":"product_cat-polypol","9":"product_cat-ropa_tradicional","10":"product_tag-blusa-artesanal","11":"product_tag-blusa-de-lino","12":"product_tag-moda-mexicana","13":"product_tag-ropa-de-verano","14":"product_shipping_class-fast-delivery","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blusa Orqu\u00eddea -<\/title>\n<meta name=\"description\" content=\"Luce esta blusa artesanal de 100% lino con un delicado estampado de orqu\u00eddea en color salm\u00f3n, grabado a mano en madera. Elegancia y artesan\u00eda en una sola pieza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blusa Orqu\u00eddea -\" \/>\n<meta property=\"og:description\" content=\"Luce esta blusa artesanal de 100% lino con un delicado estampado de orqu\u00eddea en color salm\u00f3n, grabado a mano en madera. Elegancia y artesan\u00eda en una sola pieza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TetereteHome\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T18:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teterete.com\/mx\/wp-content\/uploads\/2024\/08\/BLUSA-OR.png\" \/>\n\t<meta property=\"og:image:width\" content=\"808\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Teterete_Home\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/\",\"url\":\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/\",\"name\":\"Blusa Orqu\u00eddea -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teterete.com\\\/mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/BLUSA-OR.png\",\"datePublished\":\"2024-08-29T18:37:56+00:00\",\"dateModified\":\"2024-08-29T18:37:57+00:00\",\"description\":\"Luce esta blusa artesanal de 100% lino con un delicado estampado de orqu\u00eddea en color salm\u00f3n, grabado a mano en madera. Elegancia y artesan\u00eda en una sola pieza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/teterete.com\\\/mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/BLUSA-OR.png\",\"contentUrl\":\"https:\\\/\\\/teterete.com\\\/mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/BLUSA-OR.png\",\"width\":808,\"height\":808,\"caption\":\"Blusa Orqu\u00eddea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/producto\\\/blusa-orquidea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teterete.com\\\/mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/teterete.com\\\/mx\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blusa Orqu\u00eddea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teterete.com\\\/mx\\\/#website\",\"url\":\"https:\\\/\\\/teterete.com\\\/mx\\\/\",\"name\":\"\",\"description\":\"Tienda en L\u00ednea de Fina Artesanias y Dise\u00f1o Mexicano. Bellas piezas elaboradas a mano por los mejores artesanos del pa\u00eds as\u00ed como piezas de dise\u00f1o y decoraci\u00f3n con inspiraci\u00f3n artesanal.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teterete.com\\\/mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blusa Orqu\u00eddea -","description":"Luce esta blusa artesanal de 100% lino con un delicado estampado de orqu\u00eddea en color salm\u00f3n, grabado a mano en madera. Elegancia y artesan\u00eda en una sola pieza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/","og_locale":"es_ES","og_type":"article","og_title":"Blusa Orqu\u00eddea -","og_description":"Luce esta blusa artesanal de 100% lino con un delicado estampado de orqu\u00eddea en color salm\u00f3n, grabado a mano en madera. Elegancia y artesan\u00eda en una sola pieza","og_url":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/","article_publisher":"https:\/\/www.facebook.com\/TetereteHome\/","article_modified_time":"2024-08-29T18:37:57+00:00","og_image":[{"width":808,"height":808,"url":"https:\/\/teterete.com\/mx\/wp-content\/uploads\/2024\/08\/BLUSA-OR.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Teterete_Home","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/","url":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/","name":"Blusa Orqu\u00eddea -","isPartOf":{"@id":"https:\/\/teterete.com\/mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/#primaryimage"},"image":{"@id":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/#primaryimage"},"thumbnailUrl":"https:\/\/teterete.com\/mx\/wp-content\/uploads\/2024\/08\/BLUSA-OR.png","datePublished":"2024-08-29T18:37:56+00:00","dateModified":"2024-08-29T18:37:57+00:00","description":"Luce esta blusa artesanal de 100% lino con un delicado estampado de orqu\u00eddea en color salm\u00f3n, grabado a mano en madera. Elegancia y artesan\u00eda en una sola pieza","breadcrumb":{"@id":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/#primaryimage","url":"https:\/\/teterete.com\/mx\/wp-content\/uploads\/2024\/08\/BLUSA-OR.png","contentUrl":"https:\/\/teterete.com\/mx\/wp-content\/uploads\/2024\/08\/BLUSA-OR.png","width":808,"height":808,"caption":"Blusa Orqu\u00eddea"},{"@type":"BreadcrumbList","@id":"https:\/\/teterete.com\/mx\/producto\/blusa-orquidea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teterete.com\/mx\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/teterete.com\/mx\/shop\/"},{"@type":"ListItem","position":3,"name":"Blusa Orqu\u00eddea"}]},{"@type":"WebSite","@id":"https:\/\/teterete.com\/mx\/#website","url":"https:\/\/teterete.com\/mx\/","name":"","description":"Tienda en L\u00ednea de Fina Artesanias y Dise\u00f1o Mexicano. Bellas piezas elaboradas a mano por los mejores artesanos del pa\u00eds as\u00ed como piezas de dise\u00f1o y decoraci\u00f3n con inspiraci\u00f3n artesanal.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teterete.com\/mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/product\/11737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/comments?post=11737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/media\/11738"}],"wp:attachment":[{"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/media?parent=11737"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/product_brand?post=11737"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/product_cat?post=11737"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/teterete.com\/mx\/wp-json\/wp\/v2\/product_tag?post=11737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}